{"id":28,"count":4,"description":"","link":"https:\/\/politicalgadgets.com\/words\/category\/government-business\/","name":"Government Business","slug":"government-business","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Government Business Archives - Political Gadgets - Articles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/politicalgadgets.com\/words\/category\/government-business\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Government Business Archives - Political Gadgets - Articles\" \/>\n<meta property=\"og:url\" content=\"https:\/\/politicalgadgets.com\/words\/category\/government-business\/\" \/>\n<meta property=\"og:site_name\" content=\"Political Gadgets - Articles\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/politicalgadgets.com\\\/words\\\/category\\\/government-business\\\/\",\"url\":\"https:\\\/\\\/politicalgadgets.com\\\/words\\\/category\\\/government-business\\\/\",\"name\":\"Government Business Archives - Political Gadgets - Articles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/politicalgadgets.com\\\/words\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/politicalgadgets.com\\\/words\\\/category\\\/government-business\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/politicalgadgets.com\\\/words\\\/category\\\/government-business\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/politicalgadgets.com\\\/words\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Government Business\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/politicalgadgets.com\\\/words\\\/#website\",\"url\":\"https:\\\/\\\/politicalgadgets.com\\\/words\\\/\",\"name\":\"Political Gadgets - Articles\",\"description\":\"Free Tools for Democracy\",\"publisher\":{\"@id\":\"https:\\\/\\\/politicalgadgets.com\\\/words\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/politicalgadgets.com\\\/words\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/politicalgadgets.com\\\/words\\\/#organization\",\"name\":\"Political Gadgets - Articles\",\"url\":\"https:\\\/\\\/politicalgadgets.com\\\/words\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/politicalgadgets.com\\\/words\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/politicalgadgets.com\\\/words\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/pignew-1.png?fit=441%2C140&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/politicalgadgets.com\\\/words\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/pignew-1.png?fit=441%2C140&ssl=1\",\"width\":441,\"height\":140,\"caption\":\"Political Gadgets - Articles\"},\"image\":{\"@id\":\"https:\\\/\\\/politicalgadgets.com\\\/words\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Government Business Archives - Political Gadgets - Articles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/politicalgadgets.com\/words\/category\/government-business\/","og_locale":"en_US","og_type":"article","og_title":"Government Business Archives - Political Gadgets - Articles","og_url":"https:\/\/politicalgadgets.com\/words\/category\/government-business\/","og_site_name":"Political Gadgets - Articles","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/politicalgadgets.com\/words\/category\/government-business\/","url":"https:\/\/politicalgadgets.com\/words\/category\/government-business\/","name":"Government Business Archives - Political Gadgets - Articles","isPartOf":{"@id":"https:\/\/politicalgadgets.com\/words\/#website"},"breadcrumb":{"@id":"https:\/\/politicalgadgets.com\/words\/category\/government-business\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/politicalgadgets.com\/words\/category\/government-business\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/politicalgadgets.com\/words\/"},{"@type":"ListItem","position":2,"name":"Government Business"}]},{"@type":"WebSite","@id":"https:\/\/politicalgadgets.com\/words\/#website","url":"https:\/\/politicalgadgets.com\/words\/","name":"Political Gadgets - Articles","description":"Free Tools for Democracy","publisher":{"@id":"https:\/\/politicalgadgets.com\/words\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/politicalgadgets.com\/words\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/politicalgadgets.com\/words\/#organization","name":"Political Gadgets - Articles","url":"https:\/\/politicalgadgets.com\/words\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/politicalgadgets.com\/words\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/politicalgadgets.com\/words\/wp-content\/uploads\/2021\/09\/pignew-1.png?fit=441%2C140&ssl=1","contentUrl":"https:\/\/i0.wp.com\/politicalgadgets.com\/words\/wp-content\/uploads\/2021\/09\/pignew-1.png?fit=441%2C140&ssl=1","width":441,"height":140,"caption":"Political Gadgets - Articles"},"image":{"@id":"https:\/\/politicalgadgets.com\/words\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/politicalgadgets.com\/words\/wp-json\/wp\/v2\/categories\/28","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicalgadgets.com\/words\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/politicalgadgets.com\/words\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/politicalgadgets.com\/words\/wp-json\/wp\/v2\/posts?categories=28"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}